{"id":502,"date":"2023-11-23T12:07:17","date_gmt":"2023-11-23T11:07:17","guid":{"rendered":"https:\/\/dreamymegane.com\/?p=502"},"modified":"2025-05-07T03:11:00","modified_gmt":"2025-05-07T01:11:00","slug":"guide-journee-suwon","status":"publish","type":"post","link":"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/","title":{"rendered":"Une journ\u00e9e \u00e0 Suwon"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull is-light has-parallax ona-hero\" style=\"min-height:330px\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-30 has-background-dim\" style=\"background-color:#111111\"><\/span><div role=\"img\" class=\"wp-block-cover__image-background wp-image-505 has-parallax\" style=\"background-position:50% 50%;background-image:url(https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/suwon-1.jpg)\"><\/div><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-group is-layout-constrained wp-container-1 wp-block-group-is-layout-constrained\">\n<h1 class=\"wp-block-heading alignfull has-text-align-center has-light-color has-text-color has-x-large-font-size\" id=\"hello-i-m-ona-and-this-is-my-personal-travel-journal\">Une journ\u00e9e \u00e0 Suwon<\/h1>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-4 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center\">Suwon est dans le top de mes destinations pr\u00e9f\u00e9r\u00e9es en Cor\u00e9e, et pourtant, elle est situ\u00e9e juste \u00e0 c\u00f4t\u00e9 de S\u00e9oul ! La ville est compos\u00e9e de plusieurs quartiers assez distincts, dont un qui comporte la majorit\u00e9 des lieux et monuments historiques. Je suis venue plusieurs fois \u00e0 Suwon et j\u2019ai vraiment ador\u00e9 ce quartier pour sa muraille, ses maisons traditionnelles r\u00e9am\u00e9nag\u00e9es en caf\u00e9s et boutiques et ses petites rues pleines de charme !<\/p><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 ez-toc-wrap-center counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Petit sommaire<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #df93af;color:#df93af\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #df93af;color:#df93af\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/#Comment_se_rendre_a_Suwon\" >Comment se rendre \u00e0 Suwon ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/#Les_choses_a_voir_et_a_faire_a_Suwon\" >Les choses \u00e0 voir et \u00e0 faire \u00e0 Suwon !<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/#Quelques_adresses_de_boutiques_pour_soutenir_les_createurs_a_Suwon\" >Quelques adresses de boutiques pour soutenir les cr\u00e9ateurs \u00e0 Suwon !<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/#Activites_a_faire_les_jours_de_pluie\" >Activit\u00e9s \u00e0 faire les jours de pluie<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/#Ou_manger_et_boire_a_Suwon\" >O\u00f9 manger et boire \u00e0 Suwon ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/#Me_suivre\" >Me suivre<\/a><\/li><\/ul><\/nav><\/div>\n\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide has-border-color is-layout-flex wp-container-6 wp-block-columns-is-layout-flex\" style=\"border-color:#df93af;border-width:1px;border-radius:20px;padding-top:var(--wp--preset--spacing--20);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center\">Vous souhaitez soutenir mon travail ou simplement me donner un peu d\u2019amour ?<br>Cet article contient sans doute des liens affili\u00e9s, ce qui signifie qu\u2019en cliquant sur ces liens, je peux recevoir une petite commission sans aucun frais suppl\u00e9mentaire pour vous ! Si vous souhaitez me soutenir dans mon travail ou simplement me remercier pour tous les conseils et bonnes adresses, passez par ces petits liens, \u00e7a ne vous co\u00fbte rien de plus, mais \u00e7a peut vraiment m\u2019aider !<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-8 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center has-text-color\" style=\"color:#df93af\"><span class=\"ez-toc-section\" id=\"Comment_se_rendre_a_Suwon\"><\/span>Comment se rendre \u00e0 Suwon ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-10 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Vous avez plusieurs options pour vous rendre \u00e0 Suwon depuis S\u00e9oul : en m\u00e9tro, en bus, en voiture personnelle, en train ou en taxi.<\/p>\n\n\n\n<p>Pour aller dans la partie de la ville dont je parlais juste au dessus, il vous faudra prendre le m\u00e9tro ligne 1 et descendre \u00e0 la station \u201cSuwon\u201d. Le trajet dure 1h environ, en fonction de votre station de d\u00e9part. Donc pensez \u00e0 bien charger votre t\u00e9l\u00e9phone ou \u00e0 prendre un livre ! Pour vous rapprocher un peu des lieux d\u2019int\u00e9r\u00eat vous pourrez ensuite prendre un bus de ville pour quelques arr\u00eats.<\/p>\n\n\n\n<p>Il est \u00e9galement possible de prendre le bus (bus rouge) depuis certaines stations de m\u00e9tro \u00e0 S\u00e9oul. Mon amie prenait g\u00e9n\u00e9ralement le bus 7770 \u00e0 la station Sadang (lignes 2 et 4). Depuis Sadang, le trajet dure environ 55 minutes et vous d\u00e9pose juste \u00e0 c\u00f4t\u00e9 de la forteresse ! Jetez un coup d&#8217;\u0153il sur <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.nhn.android.nmap&amp;hl=en_US\">Naver Map<\/a> ou <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=net.daum.android.map&amp;hl=en_US\">Kakao Map<\/a> pour trouver le trajet le plus avantageux pour vous. Je crois que de ces deux options, c&#8217;est ma pr\u00e9f\u00e9r\u00e9e.<\/p>\n\n\n\n<p>Si vous le souhaitez, vous pouvez \u00e9galement r\u00e9server <a href=\"https:\/\/www.trazy.com\/experience\/detail\/korean-folk-village-suwon-hwaseong-fortress-one-day-tour-from-seoul?ref=DM1448&amp;label=Suwon&amp;ad_id=7111\" target=\"_blank\" rel=\"noreferrer noopener\">une journ\u00e9e avec un guide<\/a> pour d\u00e9couvrir Suwon ! Le pack que j&#8217;ai trouv\u00e9 propose notamment la visite du village folklorique cor\u00e9en, une balade \u00e0 la forteresse, la d\u00e9couverte du march\u00e9 Nammun. Vous pouvez voir le d\u00e9tail de la journ\u00e9e directement <a href=\"https:\/\/www.trazy.com\/experience\/detail\/korean-folk-village-suwon-hwaseong-fortress-one-day-tour-from-seoul?ref=DM1448&amp;label=Suwon&amp;ad_id=7111\" target=\"_blank\" rel=\"noreferrer noopener\">ici<\/a>.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignwide is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-15 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_171240-768x1024.jpg\" alt=\"forteresse suwon\" class=\"wp-image-517\" srcset=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_171240-768x1024.jpg 768w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_171240-225x300.jpg 225w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_171240-1152x1536.jpg 1152w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_171240-1536x2048.jpg 1536w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_171240-1170x1560.jpg 1170w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_171240-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_121022-768x1024.jpg\" alt=\"farm to hanok\" class=\"wp-image-518\" srcset=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_121022-768x1024.jpg 768w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_121022-225x300.jpg 225w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_121022-1152x1536.jpg 1152w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_121022-1536x2048.jpg 1536w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_121022-1170x1560.jpg 1170w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_121022-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_155138-768x1024.jpg\" alt=\"palais suwon\" class=\"wp-image-519\" srcset=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_155138-768x1024.jpg 768w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_155138-225x300.jpg 225w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_155138-1152x1536.jpg 1152w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_155138-1536x2048.jpg 1536w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_155138-1170x1560.jpg 1170w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_155138-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"http:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_160024-768x1024.jpg\" alt=\"rues de suwon\" class=\"wp-image-520\" srcset=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_160024-768x1024.jpg 768w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_160024-225x300.jpg 225w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_160024-1152x1536.jpg 1152w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_160024-1536x2048.jpg 1536w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_160024-1170x1560.jpg 1170w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_160024-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-text-color\" style=\"color:#df93af\"><span class=\"ez-toc-section\" id=\"Les_choses_a_voir_et_a_faire_a_Suwon\"><\/span>Les choses \u00e0 voir et \u00e0 faire \u00e0 Suwon !<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-18 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Gangneung n\u2019est pas la destination qui regroupe le plus de choses \u00e0 faire mais qui saura satisfaire vos envies d\u2019\u00e9vasion, le temps d\u2019une journ\u00e9e ou d\u2019un week-end. Il s\u2019agit d\u2019une liste non exhaustive mais qui regroupe mes petits coups de c\u0153ur !<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignfull are-vertically-aligned-center has-background is-layout-flex wp-container-21 wp-block-columns-is-layout-flex\" style=\"background-color:#faf4ed\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h4 class=\"wp-block-heading has-text-color\" style=\"color:#df93af\">La forteresse de Hwaseong (\uc218\uc6d0\ud654\uc131)<\/h4>\n\n\n\n<p>La forteresse de Hwaseong est l&#8217;endroit le plus populaire de Suwon ! Construite en 1796, la forteresse de Hwaseong poss\u00e8de un passif historique \u00e0 la fois triste et dramatique et qui est devenu le sujet de nombreux dramas et films cor\u00e9ens. Si vous \u00eates fan de K-Culture, il y a de fortes chances que vous connaissiez cette histoire.<br>Si vous suivez la muraille et que vous montez jusqu\u2019\u00e0 Seojangdae (\ud654\uc131\uc7a5\ub300), vous aurez un point de vue exceptionnel sur la ville !<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-border-color\" style=\"border-color:#df93af;border-width:1px\"><tbody><tr><td>\ud83d\udccd\u00a0Adresse : 320-2 Yeonghwa-dong, Jangan-gu, Suwon-si, Gyeonggi-do \/ \uacbd\uae30 \uc218\uc6d0\uc2dc \ud314\ub2ec\uad6c \uc7a5\uc548\ub3d9 334<br>\ud83d\udcc5\u00a0Jours d\u2019ouverture : Tous les jours<br>\ud83d\udd50\u00a0Horaires : 24h\/24<br>\ud83c\udf9f\ufe0f Tarif : Gratuit<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_143521-768x1024.jpg\" alt=\"forteresse de Hwaseong\" class=\"wp-image-506\" style=\"aspect-ratio:0.75;width:352px;height:auto\" srcset=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_143521-768x1024.jpg 768w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_143521-225x300.jpg 225w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_143521-1152x1536.jpg 1152w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_143521-1536x2048.jpg 1536w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_143521-1170x1560.jpg 1170w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_143521-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-24 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_154043-768x1024.jpg\" alt=\"Palais Hwaseong Haenggung\" class=\"wp-image-507\" style=\"aspect-ratio:0.75;width:378px;height:auto\" srcset=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_154043-768x1024.jpg 768w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_154043-225x300.jpg 225w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_154043-1152x1536.jpg 1152w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_154043-1536x2048.jpg 1536w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_154043-1170x1560.jpg 1170w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_154043-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h4 class=\"wp-block-heading has-text-color\" style=\"color:#df93af\">Le Palais Hwaseong Haenggung (\ud654\uc131\ud589\uad81)<\/h4>\n\n\n\n<p>Le Palais Hwaseong Haenggung est une ancienne demeure utilis\u00e9e temporairement par le roi pour s\u2019y reposer ou trouver refuge en temps de guerre. L&#8217;ensemble du palais n&#8217;est pas tr\u00e8s grand et se visite tr\u00e8s rapidement. Si vous avez d\u00e9j\u00e0 visit\u00e9 les palais de S\u00e9oul, vous ne serez sans doute pas vraiment impressionn\u00e9 par celui-ci, mais je trouve que la visite reste super agr\u00e9able, et c&#8217;est un bon combo avec la forteresse et la mont\u00e9e \u00e0 travers la for\u00eat.<\/p>\n\n\n\n<p>Astuce : Juste \u00e0 c\u00f4t\u00e9 du palais se trouve un mus\u00e9e d&#8217;art. Si vous avez un peu de temps devant vous, montez sur le toit du mus\u00e9e qui vous permet d&#8217;avoir une super vue sur le palais !<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-border-color\" style=\"border-color:#df93af;border-width:1px\"><tbody><tr><td>\ud83d\udccd\u00a0Adresse : 825 Jeongjo-ro, Paldal-gu, Suwon-si, Gyeonggi-do \/ \uacbd\uae30 \uc218\uc6d0\uc2dc \ud314\ub2ec\uad6c \uc815\uc870\ub85c 825<br>\ud83d\udcc5\u00a0Jours d\u2019ouverture : Tous les jours<br>\ud83d\udd50\u00a0Horaires : 09h00-18h00<br>\ud83c\udf9f\ufe0f Tarif : Gratuit<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignfull are-vertically-aligned-center has-background is-layout-flex wp-container-27 wp-block-columns-is-layout-flex\" style=\"background-color:#faf4ed\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h4 class=\"wp-block-heading has-text-color\" style=\"color:#df93af\">Le Temple Daeseungwon (\ub300\uc2b9\uc6d0)<\/h4>\n\n\n\n<p>Nich\u00e9 en contrebas de la forteresse de Suwon, le temple Daeseungwon est un tout petit temple de quelques b\u00e2tisses avec une grande statue de Bouddha en or en son centre.<\/p>\n\n\n\n<p>En suivant la petite rue qui descend, vous tomberez sur la rue Haenggung Street (\ud589\uad81\uae38) qui est super charmante ! En partant sur votre gauche, vous arriverez naturellement sur la grande place juste en face du Palais Hwaseong Haenggung !<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-border-color\" style=\"border-color:#df93af;border-width:1px\"><tbody><tr><td>\ud83d\udccd\u00a0Adresse : 56-3 Namchang-dong, Paldal-gu, Suwon-si, Gyeonggi-do \/ \uacbd\uae30 \uc218\uc6d0\uc2dc \ud314\ub2ec\uad6c \ud589\uad81\ub85c26\ubc88\uae38 38<br>\ud83d\udcc5\u00a0Jours d\u2019ouverture : Tous les jours<br>\ud83d\udd50\u00a0Horaires : 24h\/24 (mais \u00e9viter de venir le soir pour ne pas d\u00e9ranger)<br>\ud83c\udf9f\ufe0f Tarif : Gratuit<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_140004-768x1024.jpg\" alt=\"Temple Daeseungwon\" class=\"wp-image-508\" style=\"aspect-ratio:0.75;width:349px;height:auto\" srcset=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_140004-768x1024.jpg 768w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_140004-225x300.jpg 225w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_140004-1152x1536.jpg 1152w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_140004-1536x2048.jpg 1536w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_140004-1170x1560.jpg 1170w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_140004-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide are-vertically-aligned-center is-layout-flex wp-container-30 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_145850-768x1024.jpg\" alt=\"lac Yongyeon suwon\" class=\"wp-image-509\" style=\"aspect-ratio:0.75;width:340px;height:auto\" srcset=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_145850-768x1024.jpg 768w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_145850-225x300.jpg 225w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_145850-1152x1536.jpg 1152w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_145850-1536x2048.jpg 1536w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_145850-1170x1560.jpg 1170w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20220602_145850-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h4 class=\"wp-block-heading has-text-color\" style=\"color:#df93af\">Le lac Yongyeon (\uc6a9\uc5f0)<\/h4>\n\n\n\n<p>Si vous suivez toute la promenade le long de la muraille en allant vers l\u2019ouest, vous tomberez forc\u00e9ment sur ce petit lac ! Avec ses arbres et ses saules pleureurs, c\u2019est l\u2019un des endroits les plus charmants du quartier ! Il y a m\u00eame des canards et des oies qui se baladent ou se reposent le long de l&#8217;eau !<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-border-color\" style=\"border-color:#df93af;border-width:1px\"><tbody><tr><td>\ud83d\udccd\u00a0Adresse : 190 Yeonmu-dong, Jangan-gu, Suwon-si, Gyeonggi-do \/ \uacbd\uae30 \uc218\uc6d0\uc2dc \uc7a5\uc548\uad6c \uc5f0\ubb34\ub3d9<br>\ud83d\udcc5\u00a0Jours d\u2019ouverture : Tous les jours<br>\ud83d\udd50\u00a0Horaires : 24h\/24<br>\ud83c\udf9f\ufe0f Tarif : Gratuit<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignfull are-vertically-aligned-center has-background is-layout-flex wp-container-33 wp-block-columns-is-layout-flex\" style=\"background-color:#faf4ed\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h4 class=\"wp-block-heading has-text-color\" style=\"color:#df93af\">Flying Suwon (\ud50c\ub77c\uc789\uc218\uc6d0)<\/h4>\n\n\n\n<p>Si vous souhaitez faire une activit\u00e9 originale, c\u2019est ce qu\u2019il vous faut ! Flying Suwon est situ\u00e9 juste \u00e0 c\u00f4t\u00e9 du parking de la forteresse Suwon Hwaseong, ou tout au bout \u00e0 droite si vous marchez le long de la muraille ! Montez dans une montgolfi\u00e8re et profitez de Suwon d&#8217;en haut ! C&#8217;est un peu cher mais la vue est incroyable, surtout quand il fait beau et clair. Je pense que c&#8217;est l&#8217;une des choses les plus cool \u00e0 Suwon, et j&#8217;ai d\u00e9j\u00e0 h\u00e2te de le faire !<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-border-color\" style=\"border-color:#df93af;border-width:1px\"><tbody><tr><td>\ud83d\udccd\u00a0Adresse : 255-4 \uc9c0\ub3d9 Paldal-gu, Suwon-si, Gyeonggi-do \/ \uacbd\uae30 \uc218\uc6d0\uc2dc \ud314\ub2ec\uad6c \uc9c0\ub3d9 255-4<br>\ud83d\udcc5\u00a0Jours d\u2019ouverture : Tous les jours<br>\ud83d\udd50\u00a0Horaires : du lundi au vendredi : 14h00-22h30 \/ samedi et dimanche :<br>\ud83c\udf9f\ufe0f\u00a0Tarif : Adulte : 20000w \/ Jeune : 18000w \/ Enfant : 14000w<br>\ud83c\udf10 Site web : <a href=\"http:\/\/www.flyingsuwon.com\/?ckattempt=1\">Flying Suwon<\/a> (en cor\u00e9en)<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img decoding=\"async\" width=\"758\" height=\"1024\" src=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/flying-suwon-2-758x1024.jpg\" alt=\"flying suwon\" class=\"wp-image-510\" style=\"aspect-ratio:0.740234375;width:338px;height:auto\" srcset=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/flying-suwon-2-758x1024.jpg 758w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/flying-suwon-2-222x300.jpg 222w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/flying-suwon-2-768x1038.jpg 768w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/flying-suwon-2.jpg 917w\" sizes=\"(max-width: 758px) 100vw, 758px\" \/><figcaption class=\"wp-element-caption\">pic from Flying Suwon<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-36 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/\uc218\uc6d0\uc804\ud1b5\ubb38\ud654\uad00-1024x683.jpg\" alt=\"\" class=\"wp-image-526\" srcset=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/\uc218\uc6d0\uc804\ud1b5\ubb38\ud654\uad00-1024x683.jpg 1024w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/\uc218\uc6d0\uc804\ud1b5\ubb38\ud654\uad00-300x200.jpg 300w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/\uc218\uc6d0\uc804\ud1b5\ubb38\ud654\uad00-768x512.jpg 768w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/\uc218\uc6d0\uc804\ud1b5\ubb38\ud654\uad00-1536x1024.jpg 1536w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/\uc218\uc6d0\uc804\ud1b5\ubb38\ud654\uad00-1170x780.jpg 1170w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/\uc218\uc6d0\uc804\ud1b5\ubb38\ud654\uad00.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h4 class=\"wp-block-heading has-text-color\" style=\"color:#df93af\">Centre culturel traditionnel de Suwon (\uc218\uc6d0\uc804\ud1b5\ubb38\ud654\uad00)<\/h4>\n\n\n\n<p>N&#8217;oublions pas d&#8217;ajouter un peu de culture et de mus\u00e9es ! Le centre culturel traditionnel de Suwon est un lieu o\u00f9 habitants et touristes viennent se d\u00e9tendre et d\u00e9couvrir la culture locale des habitants de la ville. Dans ce centre, on trouve une dizaine de b\u00e2timents cor\u00e9ens traditionnels, un petit mus\u00e9e, des boutiques de souvenirs, des lieux d&#8217;\u00e9tude et des caf\u00e9s. Les visiteurs trouveront \u00e9galement un magnifique temple dans lequel se d\u00e9roulent chaque matin des s\u00e9ances de m\u00e9ditation et de yoga.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-border-color\" style=\"border-color:#df93af;border-width:1px\"><tbody><tr><td>\ud83d\udccd\u00a0Adresse : 18-11 Haenggung-dong, Paldal-gu, Suwon-si, Gyeonggi-do \/ \uacbd\uae30 \uc218\uc6d0\uc2dc \ud314\ub2ec\uad6c \uc815\uc870\ub85c 893<br>\ud83d\udcc5\u00a0Jours d\u2019ouverture : Tous les jours sauf le lundi<br>\ud83d\udd50\u00a0Horaires : 09h00-18h00<br>\ud83c\udf9f\ufe0f\u00a0Tarif : Gratuit<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignfull are-vertically-aligned-center has-background is-layout-flex wp-container-39 wp-block-columns-is-layout-flex\" style=\"background-color:#faf4ed\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h4 class=\"wp-block-heading has-text-color\" style=\"color:#df93af\">Le mus\u00e9e Suwon Hwaseong (\uc218\uc6d0\ud654\uc131\ubc15\ubb3c\uad00)<\/h4>\n\n\n\n<p>Si vous \u00eates un peu curieux.euse de savoir pourquoi le roi a-t-il choisi de d\u00e9placer la capitale \u00e0 Hwaseong ou dans quel contexte la forteresse a-t-elle \u00e9t\u00e9 construite, vous trouverez toutes les r\u00e9ponses en visitant le Mus\u00e9e de Suwon Hwaseong !<br>On y trouve une tr\u00e8s grande quantit\u00e9 de documents d\u00e9taill\u00e9s mais aussi des lettres (lettres confidentielles \u00e9crites par le roi Jeongjo lui-m\u00eame) et art\u00e9facts de l\u2019\u00e9poque. Le mus\u00e9e a \u00e9t\u00e9 construit en 2009 pour favoriser l&#8217;\u00e9ducation sur ce point sp\u00e9cifique de l&#8217;histoire. Ici, vous pourrez donc en apprendre davantage sur les personnes qui ont fait entrer la Cor\u00e9e dans un nouvel \u00e2ge d\u2019or.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-border-color\" style=\"border-color:#df93af;border-width:1px\"><tbody><tr><td>\ud83d\udccd\u00a0Adresse : 21 Changnyong-daero, Paldal-gu, Suwon-si, Gyeonggi-do \/ \uacbd\uae30 \uc218\uc6d0\uc2dc \ud314\ub2ec\uad6c \ucc3d\ub8e1\ub300\ub85c 21 \uc218\uc6d0\ud654\uc131\ubc15\ubb3c\uad00<br>\ud83d\udcc5\u00a0Jours d\u2019ouverture : Tous les jours sauf le lundi<br>\ud83d\udd50\u00a0Horaires : 09h00-18h00<br>\ud83c\udf9f\ufe0f Tarif : Gratuit<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"699\" height=\"466\" src=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/musee-Suwon-Hwaseong-2.jpg\" alt=\"\" class=\"wp-image-523\" srcset=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/musee-Suwon-Hwaseong-2.jpg 699w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/musee-Suwon-Hwaseong-2-300x200.jpg 300w\" sizes=\"(max-width: 699px) 100vw, 699px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"699\" height=\"466\" src=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/musee-Suwon-Hwaseong.jpg\" alt=\"\" class=\"wp-image-522\" srcset=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/musee-Suwon-Hwaseong.jpg 699w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/musee-Suwon-Hwaseong-300x200.jpg 300w\" sizes=\"(max-width: 699px) 100vw, 699px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading alignwide has-text-align-center has-text-color\" style=\"color:#df93af\"><span class=\"ez-toc-section\" id=\"Quelques_adresses_de_boutiques_pour_soutenir_les_createurs_a_Suwon\"><\/span>Quelques adresses de boutiques pour soutenir les cr\u00e9ateurs \u00e0 Suwon !<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<div class=\"wp-block-columns alignfull are-vertically-aligned-center is-layout-flex wp-container-42 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" width=\"844\" height=\"844\" src=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/wynd.png\" alt=\"\" class=\"wp-image-524\" style=\"aspect-ratio:1;width:308px;height:auto\" srcset=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/wynd.png 844w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/wynd-300x300.png 300w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/wynd-150x150.png 150w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/wynd-768x768.png 768w\" sizes=\"(max-width: 844px) 100vw, 844px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h4 class=\"wp-block-heading has-text-color\" style=\"color:#df93af\">wynd<\/h4>\n\n\n\n<p>wynd est une boutique de v\u00eatements d\u00e9contract\u00e9s et de haute qualit\u00e9 pour homme. Comme il g\u00e8re cet espace seul, contactez-le en Dm sur Instagram pour voir avec lui s&#8217;il est pr\u00e9sent au showroom avant de venir !<\/p>\n\n\n\n<ul>\n<li>Adresse : 17 Changnyong-daero 38beon-gil, Paldal-gu, Suwon \/ \uacbd\uae30 \uc218\uc6d0\uc2dc \ud314\ub2ec\uad6c \ucc3d\ub8e1\ub300\ub85c38\ubc88\uae38 17<\/li>\n\n\n\n<li>Instagram : <a href=\"https:\/\/www.instagram.com\/wynd_shop\" target=\"_blank\" rel=\"noreferrer noopener\">WYND<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignfull are-vertically-aligned-center has-background is-layout-flex wp-container-45 wp-block-columns-is-layout-flex\" style=\"background-color:#faf4ed\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h4 class=\"wp-block-heading has-text-color\" style=\"color:#df93af\">Bendito et \u00e9t\u00e9 (\ubca4\ub514\ud1a0\uc900&amp;\uc5d0\ub5bc)<\/h4>\n\n\n\n<p>Bendito et \u00e9t\u00e9 est une petite boutique de bijoux travaill\u00e9s soigneusement \u00e0 la main par un couple adorable !<\/p>\n\n\n\n<ul>\n<li>Adresse : 38 Changnyong-daero, Paldal-gu, Suwon \/ \uacbd\uae30 \uc218\uc6d0\uc2dc \ud314\ub2ec\uad6c \ucc3d\ub8e1\ub300\ub85c 38<\/li>\n\n\n\n<li>Jours d\u2019ouverture et horaires : 11h30-19h30 (ferm\u00e9 le mardi)<\/li>\n\n\n\n<li>Leur site : <a href=\"https:\/\/smartstore.naver.com\/bendito_n_ete\" target=\"_blank\" rel=\"noreferrer noopener\">Bendito et \u00e9t\u00e9<\/a><\/li>\n\n\n\n<li>Instagram : <a href=\"https:\/\/www.instagram.com\/bendito_n_ete\" target=\"_blank\" rel=\"noreferrer noopener\">Bendito et \u00e9t\u00e9<\/a><\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_145534-768x1024.jpg\" alt=\"Bendito et \u00e9t\u00e9 boutique suwon\" class=\"wp-image-512\" style=\"aspect-ratio:0.75;width:303px;height:auto\" srcset=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_145534-768x1024.jpg 768w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_145534-225x300.jpg 225w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_145534-1152x1536.jpg 1152w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_145534-1536x2048.jpg 1536w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_145534-1170x1560.jpg 1170w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_145534-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide are-vertically-aligned-center is-layout-flex wp-container-48 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" width=\"813\" height=\"847\" src=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/sol-sol-2.png\" alt=\"\" class=\"wp-image-525\" style=\"aspect-ratio:0.9598583234946871;width:323px;height:auto\" srcset=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/sol-sol-2.png 813w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/sol-sol-2-288x300.png 288w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/sol-sol-2-768x800.png 768w\" sizes=\"(max-width: 813px) 100vw, 813px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h4 class=\"wp-block-heading has-text-color\" style=\"color:#df93af\">Sol Sol (\uc194\uc194)<\/h4>\n\n\n\n<p>Un caf\u00e9 tout mimi pour se poser et papoter entre ami.e.s !<\/p>\n\n\n\n<ul>\n<li>Adresse : Suwon-si, Paldal-gu, Namsu-dong, 16-20 \/ \uacbd\uae30 \uc218\uc6d0\uc2dc \ud314\ub2ec\uad6c \ucc3d\ub8e1\ub300\ub85c 42<\/li>\n\n\n\n<li>Jours et horaires d\u2019ouverture : en semaine 8h00 \u00e0 20h00, week-end et jours f\u00e9ri\u00e9s de 11h00 \u00e0 20h00<\/li>\n\n\n\n<li>Instagram : <a href=\"https:\/\/www.instagram.com\/solsol_island\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sol Sol<\/a> <\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-text-color\" style=\"color:#df93af\"><span class=\"ez-toc-section\" id=\"Activites_a_faire_les_jours_de_pluie\"><\/span>Activit\u00e9s \u00e0 faire les jours de pluie<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"has-text-align-center\">Vous venez un jour de pluie ou vous souhaitez simplement ajouter une activit\u00e9 diff\u00e9rente \u00e0 votre journ\u00e9e \u00e0 Suwon ? Dans cette partie, je vais ajouter des activit\u00e9s ou lieux que je trouve ou fur et \u00e0 mesure de mes visites ^^<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.trazy.com\/experience\/detail\/korean-tea-culture-experience-in-suwon?ref=DM1448&amp;label=Suwon&amp;ad_id=8337\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"124\" src=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2025\/05\/ceremonie-the-suwon-1024x124.png\" alt=\"\" class=\"wp-image-2969\" srcset=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2025\/05\/ceremonie-the-suwon-1024x124.png 1024w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2025\/05\/ceremonie-the-suwon-300x36.png 300w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2025\/05\/ceremonie-the-suwon-768x93.png 768w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2025\/05\/ceremonie-the-suwon-1170x141.png 1170w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2025\/05\/ceremonie-the-suwon.png 1492w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.trazy.com\/experience\/detail\/suwon-aqua-planet-gwanggyo-discount-ticket?ref=DM1448&amp;label=Suwon&amp;ad_id=8336\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"124\" src=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2025\/05\/aquaplanet-suwon-2-1024x124.png\" alt=\"\" class=\"wp-image-2968\" srcset=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2025\/05\/aquaplanet-suwon-2-1024x124.png 1024w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2025\/05\/aquaplanet-suwon-2-300x36.png 300w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2025\/05\/aquaplanet-suwon-2-768x93.png 768w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2025\/05\/aquaplanet-suwon-2-1170x141.png 1170w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2025\/05\/aquaplanet-suwon-2.png 1492w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-text-color\" style=\"color:#df93af\"><span class=\"ez-toc-section\" id=\"Ou_manger_et_boire_a_Suwon\"><\/span>O\u00f9 manger et boire \u00e0 Suwon ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-55 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Les deux fois o\u00f9 je suis venue suffisamment t\u00f4t pour manger le midi, je suis all\u00e9e \u00e0 la m\u00eame adresse ! Oops ! Je vous mets \u00e7a juste en dessous avec quelques noms de caf\u00e9s (et comptes Insta) et j&#8217;ajouterai d&#8217;autres adresses et recommandations au fur et \u00e0 mesure !<\/p>\n\n\n\n<ul>\n<li><a href=\"https:\/\/www.instagram.com\/farm_to_hanok\/\" target=\"_blank\" rel=\"noreferrer noopener\">Farm to Hanok<\/a> (\ud31c\ud22c\ud558\ub179) : 63-18 Sinpung-ro 23beon-gil, Sinpung-dong, Paldal-gu, Suwon \/ \uacbd\uae30 \uc218\uc6d0\uc2dc \ud314\ub2ec\uad6c \uc2e0\ud48d\ub85c23\ubc88\uae38 63-18 \ud55c\uc625 1\uce35<\/li>\n\n\n\n<li><a href=\"https:\/\/www.instagram.com\/vivre.s.v\" target=\"_blank\" rel=\"noreferrer noopener\">Vivre sa vie<\/a> (\ube44\ube0c\ub974 \uc0ac\ube44) : 193-231 Yeonmu-dong, Jangan-gu, Suwon \/ \uacbd\uae30 \uc218\uc6d0\uc2dc \uc7a5\uc548\uad6c \uacbd\uc218\ub300\ub85c743\ubc88\uae38 78<\/li>\n\n\n\n<li><a href=\"https:\/\/www.instagram.com\/cafe_eburnean\" target=\"_blank\" rel=\"noreferrer noopener\">Eburnean<\/a> (\uc5d0\ubc84\ub2cc) : Suwon, Paldal-gu, Jangan-dong, Hwaseomun-ro 31beon-gil, 9-5 \/ \uacbd\uae30 \uc218\uc6d0\uc2dc \ud314\ub2ec\uad6c \ud654\uc11c\ubb38\ub85c31\ubc88\uae38 9-5<\/li>\n\n\n\n<li><a href=\"https:\/\/www.instagram.com\/redbrickcoffeee\" target=\"_blank\" rel=\"noreferrer noopener\">Red Brick Coffeehouse<\/a> (\ub808\ub4dc\ube0c\ub9ad\ucee4\ud53c\ud558\uc6b0\uc2a4) : 110-2 Jangan-dong, Paldal-gu, Suwon \/ \uacbd\uae30 \uc218\uc6d0\uc2dc \ud314\ub2ec\uad6c \ud654\uc11c\ubb38\ub85c31\ubc88\uae38 9-8<\/li>\n\n\n\n<li><a href=\"https:\/\/www.instagram.com\/keepthat_coffee\" target=\"_blank\" rel=\"noreferrer noopener\">Keep That Coffee<\/a> (\ud0b5\ub313\ucee4\ud53c) : 14-34 Hwaseomun-ro 31beon-gil, Jangan-dong, Paldal-gu, Suwon \/ \uacbd\uae30 \uc218\uc6d0\uc2dc \ud314\ub2ec\uad6c \ud654\uc11c\ubb38\ub85c31\ubc88\uae38 14-34<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-53 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_120910-768x1024.jpg\" alt=\"Farm to Hanok\" class=\"wp-image-513\" srcset=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_120910-768x1024.jpg 768w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_120910-225x300.jpg 225w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_120910-1152x1536.jpg 1152w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_120910-1536x2048.jpg 1536w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_120910-1170x1560.jpg 1170w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_120910-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_122614-768x1024.jpg\" alt=\"Farm to Hanok\" class=\"wp-image-514\" srcset=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_122614-768x1024.jpg 768w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_122614-225x300.jpg 225w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_122614-1152x1536.jpg 1152w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_122614-1536x2048.jpg 1536w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_122614-1170x1560.jpg 1170w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_122614-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_153559-768x1024.jpg\" alt=\"caf\u00e9 Vivre sa vie\" class=\"wp-image-515\" srcset=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_153559-768x1024.jpg 768w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_153559-225x300.jpg 225w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_153559-1152x1536.jpg 1152w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_153559-1536x2048.jpg 1536w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_153559-1170x1560.jpg 1170w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_153559-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_155849-768x1024.jpg\" alt=\"caf\u00e9 Vivre sa vie\" class=\"wp-image-516\" srcset=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_155849-768x1024.jpg 768w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_155849-225x300.jpg 225w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_155849-1152x1536.jpg 1152w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_155849-1536x2048.jpg 1536w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_155849-1170x1560.jpg 1170w, https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_155849-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center\">N\u2019h\u00e9sitez pas \u00e0 venir dans mes dms Instagram pour me dire si vous allez bient\u00f4t visiter Suwon, \u00e7a me ferait super plaisir ! J\u2019esp\u00e8re que cet article sp\u00e9cial Suwon vous aidera dans la pr\u00e9paration de votre petit voyage ! Des bisous !<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\"><span class=\"ez-toc-section\" id=\"Me_suivre\"><\/span>Me suivre<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-57 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">        <div\n            class=\"spotlight-instagram-feed\"\n            data-feed-var=\"26c560d9\"\n            data-analytics=\"0\"\n            data-instance=\"502\"\n        >\n        <\/div>\n        <input type=\"hidden\" id=\"sli__f__26c560d9\" data-json='{&quot;useCase&quot;:&quot;accounts&quot;,&quot;template&quot;:&quot;row&quot;,&quot;layout&quot;:&quot;grid&quot;,&quot;numColumns&quot;:{&quot;desktop&quot;:5,&quot;phone&quot;:3,&quot;tablet&quot;:5},&quot;highlightFreq&quot;:{&quot;desktop&quot;:7},&quot;sliderNumScrollPosts&quot;:{&quot;desktop&quot;:1},&quot;sliderInfinite&quot;:true,&quot;sliderLoop&quot;:false,&quot;sliderArrowPos&quot;:{&quot;desktop&quot;:&quot;inside&quot;},&quot;sliderArrowSize&quot;:{&quot;desktop&quot;:20},&quot;sliderArrowColor&quot;:{&quot;r&quot;:255,&quot;b&quot;:255,&quot;g&quot;:255,&quot;a&quot;:1},&quot;sliderArrowBgColor&quot;:{&quot;r&quot;:0,&quot;b&quot;:0,&quot;g&quot;:0,&quot;a&quot;:0.8},&quot;sliderAutoScroll&quot;:false,&quot;sliderAutoInterval&quot;:3,&quot;postOrder&quot;:&quot;date_desc&quot;,&quot;numPosts&quot;:{&quot;desktop&quot;:5,&quot;phone&quot;:3,&quot;tablet&quot;:5},&quot;linkBehavior&quot;:{&quot;desktop&quot;:&quot;new_tab&quot;},&quot;feedWidth&quot;:{&quot;desktop&quot;:0},&quot;feedHeight&quot;:{&quot;desktop&quot;:0},&quot;feedPadding&quot;:{&quot;desktop&quot;:0,&quot;tablet&quot;:0,&quot;phone&quot;:0},&quot;imgPadding&quot;:{&quot;desktop&quot;:0,&quot;tablet&quot;:0,&quot;phone&quot;:0},&quot;textSize&quot;:{&quot;desktop&quot;:0,&quot;tablet&quot;:0,&quot;phone&quot;:0},&quot;bgColor&quot;:{&quot;r&quot;:255,&quot;g&quot;:255,&quot;b&quot;:255,&quot;a&quot;:1},&quot;hoverInfo&quot;:[&quot;insta_link&quot;,&quot;date&quot;],&quot;textColorHover&quot;:{&quot;r&quot;:255,&quot;g&quot;:255,&quot;b&quot;:255,&quot;a&quot;:1},&quot;bgColorHover&quot;:{&quot;r&quot;:0,&quot;g&quot;:0,&quot;b&quot;:0,&quot;a&quot;:0.5},&quot;showHeader&quot;:{&quot;desktop&quot;:false},&quot;headerInfo&quot;:{&quot;desktop&quot;:[&quot;profile_pic&quot;,&quot;bio&quot;]},&quot;headerAccount&quot;:null,&quot;headerStyle&quot;:{&quot;desktop&quot;:&quot;normal&quot;,&quot;phone&quot;:&quot;centered&quot;},&quot;headerTextSize&quot;:{&quot;desktop&quot;:0},&quot;headerPhotoSize&quot;:{&quot;desktop&quot;:50},&quot;headerTextColor&quot;:{&quot;r&quot;:0,&quot;g&quot;:0,&quot;b&quot;:0,&quot;a&quot;:1},&quot;headerBgColor&quot;:{&quot;r&quot;:255,&quot;g&quot;:255,&quot;b&quot;:255,&quot;a&quot;:1},&quot;headerPadding&quot;:{&quot;desktop&quot;:0},&quot;customProfilePic&quot;:&quot;&quot;,&quot;customBioText&quot;:&quot;&quot;,&quot;includeStories&quot;:false,&quot;storiesInterval&quot;:5,&quot;showCaptions&quot;:{&quot;desktop&quot;:false,&quot;tablet&quot;:false},&quot;captionMaxLength&quot;:{&quot;desktop&quot;:0},&quot;captionRemoveDots&quot;:false,&quot;captionSize&quot;:{&quot;desktop&quot;:0},&quot;captionColor&quot;:{&quot;r&quot;:0,&quot;g&quot;:0,&quot;b&quot;:0,&quot;a&quot;:1},&quot;showLikes&quot;:{&quot;desktop&quot;:false,&quot;tablet&quot;:false},&quot;showComments&quot;:{&quot;desktop&quot;:false,&quot;tablet&quot;:false},&quot;lcIconSize&quot;:{&quot;desktop&quot;:14},&quot;likesIconColor&quot;:{&quot;r&quot;:0,&quot;g&quot;:0,&quot;b&quot;:0,&quot;a&quot;:1},&quot;commentsIconColor&quot;:{&quot;r&quot;:0,&quot;g&quot;:0,&quot;b&quot;:0,&quot;a&quot;:1},&quot;lightboxShowSidebar&quot;:false,&quot;lightboxCtaStyle&quot;:&quot;link&quot;,&quot;lightboxCtaDesign&quot;:{&quot;text&quot;:{&quot;color&quot;:{&quot;r&quot;:0,&quot;g&quot;:0,&quot;b&quot;:0,&quot;a&quot;:1},&quot;align&quot;:&quot;center&quot;},&quot;bgColor&quot;:{&quot;r&quot;:230,&quot;g&quot;:230,&quot;b&quot;:230,&quot;a&quot;:1},&quot;border&quot;:{&quot;radius&quot;:3}},&quot;numLightboxComments&quot;:50,&quot;showLoadMoreBtn&quot;:{&quot;desktop&quot;:false},&quot;loadMoreBtnDesign&quot;:{&quot;text&quot;:{&quot;color&quot;:{&quot;r&quot;:255,&quot;g&quot;:255,&quot;b&quot;:255,&quot;a&quot;:1},&quot;align&quot;:&quot;center&quot;},&quot;border&quot;:{&quot;radius&quot;:3},&quot;bgColor&quot;:{&quot;r&quot;:0,&quot;g&quot;:149,&quot;b&quot;:246,&quot;a&quot;:1},&quot;margin&quot;:{&quot;top&quot;:0,&quot;bottom&quot;:0,&quot;left&quot;:0,&quot;right&quot;:0}},&quot;loadMoreBtnText&quot;:&quot;Load more&quot;,&quot;loadMoreBtnScroll&quot;:true,&quot;autoload&quot;:false,&quot;showFollowBtn&quot;:{&quot;desktop&quot;:false,&quot;phone&quot;:false},&quot;followBtnText&quot;:&quot;Follow on Instagram&quot;,&quot;followBtnDesign&quot;:{&quot;text&quot;:{&quot;color&quot;:{&quot;r&quot;:255,&quot;g&quot;:255,&quot;b&quot;:255,&quot;a&quot;:1},&quot;align&quot;:&quot;center&quot;},&quot;border&quot;:{&quot;radius&quot;:3},&quot;bgColor&quot;:{&quot;r&quot;:0,&quot;g&quot;:149,&quot;b&quot;:246,&quot;a&quot;:1},&quot;margin&quot;:{&quot;top&quot;:0,&quot;bottom&quot;:0,&quot;left&quot;:0,&quot;right&quot;:0}},&quot;followBtnLocation&quot;:{&quot;desktop&quot;:&quot;bottom&quot;,&quot;phone&quot;:&quot;bottom&quot;},&quot;alignFooterButtons&quot;:{&quot;desktop&quot;:false},&quot;customCss&quot;:&quot;\\\/* Enter your custom CSS below *\\\/\\n\\n&quot;,&quot;accounts&quot;:[91],&quot;tagged&quot;:[],&quot;hashtags&quot;:[],&quot;mediaType&quot;:&quot;all&quot;,&quot;hashtagWhitelist&quot;:[],&quot;hashtagBlacklist&quot;:[],&quot;captionWhitelist&quot;:[],&quot;captionBlacklist&quot;:[],&quot;hashtagWhitelistSettings&quot;:true,&quot;hashtagBlacklistSettings&quot;:true,&quot;captionWhitelistSettings&quot;:true,&quot;captionBlacklistSettings&quot;:true,&quot;moderation&quot;:[],&quot;moderationMode&quot;:&quot;blacklist&quot;,&quot;promosVersion&quot;:2,&quot;promosEnabled&quot;:true,&quot;globalPromosEnabled&quot;:true,&quot;autoPromosEnabled&quot;:true,&quot;promoOverrides&quot;:[],&quot;feedPromo&quot;:{&quot;linkSource&quot;:{&quot;type&quot;:null},&quot;linkBehavior&quot;:{&quot;openNewTab&quot;:false,&quot;showPopupBox&quot;:false},&quot;linkText&quot;:&quot;&quot;},&quot;gaCampaignSource&quot;:&quot;&quot;,&quot;gaCampaignMedium&quot;:&quot;&quot;,&quot;gaCampaignName&quot;:&quot;&quot;,&quot;className&quot;:&quot;&quot;}' \/>\n        <input type=\"hidden\" id=\"sli__a__26c560d9\" data-json='[{&quot;id&quot;:91,&quot;type&quot;:&quot;PERSONAL&quot;,&quot;userId&quot;:&quot;24619783874279414&quot;,&quot;username&quot;:&quot;dreamymegane&quot;,&quot;bio&quot;:&quot;&quot;,&quot;customBio&quot;:&quot;&quot;,&quot;profilePicUrl&quot;:&quot;&quot;,&quot;customProfilePicUrl&quot;:&quot;http:\\\/\\\/dreamymegane.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/megane.jpg&quot;,&quot;mediaCount&quot;:&quot;979&quot;,&quot;followersCount&quot;:&quot;0&quot;,&quot;usages&quot;:[],&quot;creationDate&quot;:&quot;2023-11-07 14:56:58&quot;}]' \/>\n        <input type=\"hidden\" id=\"sli__m__26c560d9\" data-json='[]' \/>\n        <\/div>\n<\/div>\n\n\n\n<div style=\"height:8px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Suwon est dans le top de mes destinations pr\u00e9f\u00e9r\u00e9es en Cor\u00e9e, et pourtant, elle est situ\u00e9e juste \u00e0 c\u00f4t\u00e9 de S\u00e9oul ! La ville est compos\u00e9e de plusieurs quartiers assez distincts, dont un qui comporte la majorit\u00e9 des lieux et monuments historiques. Je suis venue plusieurs fois \u00e0 Suwon et j\u2019ai vraiment ador\u00e9 ce quartier [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Une journ\u00e9e \u00e0 Suwon - dreamymegane.com<\/title>\n<meta name=\"description\" content=\"Sortez de S\u00e9oul le temps d&#039;une journ\u00e9e et allez \u00e0 Suwon! Je vous aide \u00e0 d\u00e9couvrir toutes les choses \u00e0 voir et faire dans cet article !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Une journ\u00e9e \u00e0 Suwon - dreamymegane.com\" \/>\n<meta property=\"og:description\" content=\"Sortez de S\u00e9oul le temps d&#039;une journ\u00e9e et allez \u00e0 Suwon! Je vous aide \u00e0 d\u00e9couvrir toutes les choses \u00e0 voir et faire dans cet article !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/\" \/>\n<meta property=\"og:site_name\" content=\"dreamymegane.com\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-23T11:07:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-07T01:11:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_171240-768x1024.jpg\" \/>\n<meta name=\"author\" content=\"dreamymegane.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"dreamymegane.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/\"},\"author\":{\"name\":\"dreamymegane.com\",\"@id\":\"https:\/\/dreamymegane.com\/#\/schema\/person\/fcb4ff8a5fbc7f3e7c6d5b3bd0065ad2\"},\"headline\":\"Une journ\u00e9e \u00e0 Suwon\",\"datePublished\":\"2023-11-23T11:07:17+00:00\",\"dateModified\":\"2025-05-07T01:11:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/\"},\"wordCount\":1633,\"publisher\":{\"@id\":\"https:\/\/dreamymegane.com\/#\/schema\/person\/fcb4ff8a5fbc7f3e7c6d5b3bd0065ad2\"},\"image\":{\"@id\":\"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_171240-768x1024.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/\",\"url\":\"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/\",\"name\":\"Une journ\u00e9e \u00e0 Suwon - dreamymegane.com\",\"isPartOf\":{\"@id\":\"https:\/\/dreamymegane.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_171240-768x1024.jpg\",\"datePublished\":\"2023-11-23T11:07:17+00:00\",\"dateModified\":\"2025-05-07T01:11:00+00:00\",\"description\":\"Sortez de S\u00e9oul le temps d'une journ\u00e9e et allez \u00e0 Suwon! Je vous aide \u00e0 d\u00e9couvrir toutes les choses \u00e0 voir et faire dans cet article !\",\"breadcrumb\":{\"@id\":\"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/#primaryimage\",\"url\":\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_171240-scaled.jpg\",\"contentUrl\":\"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_171240-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dreamymegane.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Une journ\u00e9e \u00e0 Suwon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dreamymegane.com\/#website\",\"url\":\"https:\/\/dreamymegane.com\/\",\"name\":\"dreamymegane.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/dreamymegane.com\/#\/schema\/person\/fcb4ff8a5fbc7f3e7c6d5b3bd0065ad2\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dreamymegane.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/dreamymegane.com\/#\/schema\/person\/fcb4ff8a5fbc7f3e7c6d5b3bd0065ad2\",\"name\":\"dreamymegane.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dreamymegane.com\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/logo-blog.png\",\"contentUrl\":\"http:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/logo-blog.png\",\"width\":445,\"height\":138,\"caption\":\"dreamymegane.com\"},\"logo\":{\"@id\":\"https:\/\/dreamymegane.com\/#\/schema\/person\/image\/\"},\"sameAs\":[\"http:\/\/dreamymegane.com\"],\"url\":\"https:\/\/dreamymegane.com\/index.php\/author\/dreamymegane-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Une journ\u00e9e \u00e0 Suwon - dreamymegane.com","description":"Sortez de S\u00e9oul le temps d'une journ\u00e9e et allez \u00e0 Suwon! Je vous aide \u00e0 d\u00e9couvrir toutes les choses \u00e0 voir et faire dans cet article !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/","og_locale":"en_US","og_type":"article","og_title":"Une journ\u00e9e \u00e0 Suwon - dreamymegane.com","og_description":"Sortez de S\u00e9oul le temps d'une journ\u00e9e et allez \u00e0 Suwon! Je vous aide \u00e0 d\u00e9couvrir toutes les choses \u00e0 voir et faire dans cet article !","og_url":"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/","og_site_name":"dreamymegane.com","article_published_time":"2023-11-23T11:07:17+00:00","article_modified_time":"2025-05-07T01:11:00+00:00","og_image":[{"url":"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_171240-768x1024.jpg"}],"author":"dreamymegane.com","twitter_card":"summary_large_image","twitter_misc":{"Written by":"dreamymegane.com","Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/#article","isPartOf":{"@id":"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/"},"author":{"name":"dreamymegane.com","@id":"https:\/\/dreamymegane.com\/#\/schema\/person\/fcb4ff8a5fbc7f3e7c6d5b3bd0065ad2"},"headline":"Une journ\u00e9e \u00e0 Suwon","datePublished":"2023-11-23T11:07:17+00:00","dateModified":"2025-05-07T01:11:00+00:00","mainEntityOfPage":{"@id":"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/"},"wordCount":1633,"publisher":{"@id":"https:\/\/dreamymegane.com\/#\/schema\/person\/fcb4ff8a5fbc7f3e7c6d5b3bd0065ad2"},"image":{"@id":"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/#primaryimage"},"thumbnailUrl":"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_171240-768x1024.jpg","articleSection":["Blog"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/","url":"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/","name":"Une journ\u00e9e \u00e0 Suwon - dreamymegane.com","isPartOf":{"@id":"https:\/\/dreamymegane.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/#primaryimage"},"image":{"@id":"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/#primaryimage"},"thumbnailUrl":"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_171240-768x1024.jpg","datePublished":"2023-11-23T11:07:17+00:00","dateModified":"2025-05-07T01:11:00+00:00","description":"Sortez de S\u00e9oul le temps d'une journ\u00e9e et allez \u00e0 Suwon! Je vous aide \u00e0 d\u00e9couvrir toutes les choses \u00e0 voir et faire dans cet article !","breadcrumb":{"@id":"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/#primaryimage","url":"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_171240-scaled.jpg","contentUrl":"https:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/20230710_171240-scaled.jpg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/dreamymegane.com\/index.php\/2023\/11\/23\/guide-journee-suwon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dreamymegane.com\/"},{"@type":"ListItem","position":2,"name":"Une journ\u00e9e \u00e0 Suwon"}]},{"@type":"WebSite","@id":"https:\/\/dreamymegane.com\/#website","url":"https:\/\/dreamymegane.com\/","name":"dreamymegane.com","description":"","publisher":{"@id":"https:\/\/dreamymegane.com\/#\/schema\/person\/fcb4ff8a5fbc7f3e7c6d5b3bd0065ad2"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dreamymegane.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/dreamymegane.com\/#\/schema\/person\/fcb4ff8a5fbc7f3e7c6d5b3bd0065ad2","name":"dreamymegane.com","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dreamymegane.com\/#\/schema\/person\/image\/","url":"http:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/logo-blog.png","contentUrl":"http:\/\/dreamymegane.com\/wp-content\/uploads\/2023\/11\/logo-blog.png","width":445,"height":138,"caption":"dreamymegane.com"},"logo":{"@id":"https:\/\/dreamymegane.com\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/dreamymegane.com"],"url":"https:\/\/dreamymegane.com\/index.php\/author\/dreamymegane-com\/"}]}},"_links":{"self":[{"href":"https:\/\/dreamymegane.com\/index.php\/wp-json\/wp\/v2\/posts\/502"}],"collection":[{"href":"https:\/\/dreamymegane.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dreamymegane.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dreamymegane.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dreamymegane.com\/index.php\/wp-json\/wp\/v2\/comments?post=502"}],"version-history":[{"count":8,"href":"https:\/\/dreamymegane.com\/index.php\/wp-json\/wp\/v2\/posts\/502\/revisions"}],"predecessor-version":[{"id":2970,"href":"https:\/\/dreamymegane.com\/index.php\/wp-json\/wp\/v2\/posts\/502\/revisions\/2970"}],"wp:attachment":[{"href":"https:\/\/dreamymegane.com\/index.php\/wp-json\/wp\/v2\/media?parent=502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dreamymegane.com\/index.php\/wp-json\/wp\/v2\/categories?post=502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dreamymegane.com\/index.php\/wp-json\/wp\/v2\/tags?post=502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}